{"id":2225,"date":"2017-06-12T15:12:54","date_gmt":"2017-06-12T22:12:54","guid":{"rendered":"https:\/\/2017.sacramento.wordcamp.org\/?post_type=wcb_session&#038;p=2225"},"modified":"2017-06-12T15:12:59","modified_gmt":"2017-06-12T22:12:59","slug":"break","status":"publish","type":"wcb_session","link":"https:\/\/sacramento.wordcamp.org\/2017\/session\/break\/","title":{"rendered":"Break"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":13848243,"featured_media":0,"template":"","meta":{"_crdt_document":"","_wcpt_session_time":1505682600,"_wcpt_session_duration":3000,"_wcpt_session_type":"custom","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[],"footnotes":""},"session_track":[256835,161615,161614],"session_category":[],"class_list":["post-2225","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-room-c","wcb_track-room-b","wcb_track-room-a"],"jetpack_sharing_enabled":true,"session_date_time":{"date":"September 17, 2017","time":"2:10 pm"},"session_speakers":[],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/sacramento.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/2225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sacramento.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/sacramento.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/wcb_session"}],"author":[{"embeddable":true,"href":"https:\/\/sacramento.wordcamp.org\/2017\/wp-json\/wp\/v2\/users\/13848243"}],"version-history":[{"count":1,"href":"https:\/\/sacramento.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/2225\/revisions"}],"predecessor-version":[{"id":2226,"href":"https:\/\/sacramento.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/2225\/revisions\/2226"}],"wp:attachment":[{"href":"https:\/\/sacramento.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=2225"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/sacramento.wordcamp.org\/2017\/wp-json\/wp\/v2\/session_track?post=2225"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/sacramento.wordcamp.org\/2017\/wp-json\/wp\/v2\/session_category?post=2225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}